{"id":111,"date":"2012-08-18T16:01:30","date_gmt":"2012-08-18T14:01:30","guid":{"rendered":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017.jpg"},"modified":"2012-08-18T16:01:30","modified_gmt":"2012-08-18T14:01:30","slug":"bilder-hh2010-017","status":"inherit","type":"attachment","link":"http:\/\/geschichtsverein-haitz.org\/wordpress\/ortsansichten\/bilder-hh2010-017\/","title":{"rendered":"bilder HH2010 017"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-111","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"205\" src=\"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-300x205.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-300x205.jpg 300w, http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-1024x703.jpg 1024w, http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017.jpg 1736w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1736","height":"1192","hwstring_small":"height='87' width='128'","file":"2012\/08\/bilder-HH2010-017.jpg","sizes":{"thumbnail":{"file":"bilder-HH2010-017-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-150x150.jpg"},"medium":{"file":"bilder-HH2010-017-300x205.jpg","width":"300","height":"205","source_url":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-300x205.jpg"},"large":{"file":"bilder-HH2010-017-1024x703.jpg","width":"1024","height":"703","source_url":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-1024x703.jpg"},"post-thumbnail":{"file":"bilder-HH2010-017-940x198.jpg","width":"940","height":"198","source_url":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017-940x198.jpg"},"full":{"file":"bilder-HH2010-017.jpg","width":1736,"height":1192,"mime_type":"image\/jpeg","source_url":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":97,"source_url":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-content\/uploads\/2012\/08\/bilder-HH2010-017.jpg","_links":{"self":[{"href":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-json\/wp\/v2\/media\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-json\/wp\/v2\/comments?post=111"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":97,"href":"http:\/\/geschichtsverein-haitz.org\/wordpress\/wp-json\/wp\/v2\/pages\/97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}